{"id":185,"date":"2013-03-13T00:01:06","date_gmt":"2013-03-13T03:01:06","guid":{"rendered":"http:\/\/www.encontrajoaopessoa.com.br\/noticias\/?p=185"},"modified":"2013-03-12T16:07:39","modified_gmt":"2013-03-12T19:07:39","slug":"cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa","status":"publish","type":"post","link":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/","title":{"rendered":"Cetre inscreve servidores municipais para cursos de capacita\u00e7\u00e3o em Jo\u00e3o Pessoa"},"content":{"rendered":"<div class=\"866aa4a7c674253f40eaa20e0e3e928c\" data-index=\"1\" style=\"float: none; margin:0px;\">\n<!-- Anuncio display - global -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"8789329856\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A Prefeitura Municipal de Jo\u00e3o Pessoa (PMJP), atrav\u00e9s da Secretaria de Administra\u00e7\u00e3o, est\u00e1 oferecendo <a title=\"Cursos Diversos em Jo\u00e3o Pessoa\" href=\"http:\/\/www.encontrajoaopessoa.com.br\/c\/cursos-diversos-em-joao-pessoa.shtml\" target=\"_blank\">cursos na cidade de Jo\u00e3o Pessoa<\/a> de capacita\u00e7\u00e3o para servidores no Centro de Treinamento Miguel Arrais (Cetre), localizado \u00e0 Avenida Piau\u00ed, no Bairro dos Estados. As inscri\u00e7\u00f5es para os cursos dos meses de mar\u00e7o a abril est\u00e3o abertas e ser\u00e3o efetuadas at\u00e9 o preenchimento das vagas.<\/p>\n<p>Segundo a diretora de Recursos Humanos da Sead, L\u00edlian Coelho, ser\u00e3o formadas 77 turmas no total, divididas entre os cursos de Inform\u00e1tica, Forma\u00e7\u00e3o e Gest\u00e3o P\u00fablica. \u201cPara os cursos que estamos oferecendo inicialmente, as aulas acontecer\u00e3o nos tr\u00eas turnos, no per\u00edodo de mar\u00e7o e abril desde ano. \u00c9 importante frisar que durante todo o ano novas ofertas de cursos de forma\u00e7\u00e3o e capacita\u00e7\u00e3o devam ser apresentadas\u201d, destacou.<\/p>\n<p>Para efetuar a matr\u00edcula, os servidores dever\u00e3o dirigir-se ao Centro de Treinamento tendo em m\u00e3os uma correspond\u00eancia oficial do Cetre \u2013 encaminhada pelo chefe imediato \u2013 constando nome, matr\u00edcula e telefone dos interessados, al\u00e9m de c\u00f3pia do RG. O servidor tamb\u00e9m pode preencher a ficha de inscri\u00e7\u00e3o com todos os dados, que dever\u00e1 ser autorizada \u2013 atrav\u00e9s de assinatura e carimbo \u2013 tamb\u00e9m pelo chefe imediato.<\/p>\n<p>Programa\u00e7\u00e3o<\/p>\n<p>Na programa\u00e7\u00e3o de marco a abril, est\u00e3o previstos os cursos de Inform\u00e1tica B\u00e1sica, Contabilidade P\u00fablica para Munic\u00edpios, Comunica\u00e7\u00e3o Eficaz e Elabora\u00e7\u00e3o e Gest\u00e3o de Projetos P\u00fablicos, com in\u00edcio no dia 18 de mar\u00e7o e finaliza\u00e7\u00e3o dia 10 de abril; h\u00e1 ainda os cursos de Excel B\u00e1sico e Gest\u00e3o de Materiais no Munic\u00edpio, que acontecem entre os dias 19 de mar\u00e7o e 18 de abril; e, finalizando a capacita\u00e7\u00e3o, treinamentos direcionados ao Direito Civil Aplicado ao Munic\u00edpio e Secretariado na Administra\u00e7\u00e3o P\u00fablica, que se iniciam no dia 25 de mar\u00e7o e terminam no dia 24 de abril.<\/p>\n<p>Mais informa\u00e7\u00f5es no portal da PMJP (joaopessoa.gov.br), atrav\u00e9s do e-mail sead_cetre@joaopessoa.pb.gov.br ou pelos telefones 3214.7960\/ 3214.7925.<\/p>\n<p><em>Fonte: Prefeitura Municipal de Jo\u00e3o Pessoa<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Prefeitura Municipal de Jo\u00e3o Pessoa (PMJP), atrav\u00e9s da Secretaria de Administra\u00e7\u00e3o, est\u00e1 oferecendo cursos na cidade de Jo\u00e3o Pessoa de capacita\u00e7\u00e3o para servidores no Centro de Treinamento Miguel Arrais (Cetre), localizado \u00e0 Avenida Piau\u00ed, no Bairro dos Estados. As inscri\u00e7\u00f5es para os cursos dos meses de mar\u00e7o a abril est\u00e3o abertas e ser\u00e3o efetuadas at\u00e9 o preenchimento das vagas. Segundo a diretora de Recursos Humanos da Sead, L\u00edlian Coelho, ser\u00e3o formadas 77 turmas no total, divididas entre os cursos de Inform\u00e1tica, Forma\u00e7\u00e3o e Gest\u00e3o P\u00fablica. \u201cPara os cursos que estamos oferecendo inicialmente, as aulas acontecer\u00e3o nos tr\u00eas turnos, no <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1,7],"tags":[11],"class_list":["post-185","post","type-post","status-publish","format-standard","hentry","category-cursos-em-joao-pessoa","category-noticias-em-joao-pessoa","category-servicos-em-joao-pessoa","tag-joao-pessoa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cetre inscreve servidores municipais para cursos de capacita\u00e7\u00e3o em Jo\u00e3o Pessoa - Encontra Jo\u00e3o Pessoa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cetre inscreve servidores municipais para cursos de capacita\u00e7\u00e3o em Jo\u00e3o Pessoa - Encontra Jo\u00e3o Pessoa\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura Municipal de Jo\u00e3o Pessoa (PMJP), atrav\u00e9s da Secretaria de Administra\u00e7\u00e3o, est\u00e1 oferecendo cursos na cidade de Jo\u00e3o Pessoa de capacita\u00e7\u00e3o para servidores no Centro de Treinamento Miguel Arrais (Cetre), localizado \u00e0 Avenida Piau\u00ed, no Bairro dos Estados. As inscri\u00e7\u00f5es para os cursos dos meses de mar\u00e7o a abril est\u00e3o abertas e ser\u00e3o efetuadas at\u00e9 o preenchimento das vagas. Segundo a diretora de Recursos Humanos da Sead, L\u00edlian Coelho, ser\u00e3o formadas 77 turmas no total, divididas entre os cursos de Inform\u00e1tica, Forma\u00e7\u00e3o e Gest\u00e3o P\u00fablica. \u201cPara os cursos que estamos oferecendo inicialmente, as aulas acontecer\u00e3o nos tr\u00eas turnos, no\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Jo\u00e3o Pessoa\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-13T03:01:06+00:00\" \/>\n<meta name=\"author\" content=\"Encontra Jo\u00e3o Pessoa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Jo\u00e3o Pessoa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/\",\"url\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/\",\"name\":\"Cetre inscreve servidores municipais para cursos de capacita\u00e7\u00e3o em Jo\u00e3o Pessoa - Encontra Jo\u00e3o Pessoa\",\"isPartOf\":{\"@id\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#website\"},\"datePublished\":\"2013-03-13T03:01:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#\/schema\/person\/dcf4dbc803217a030dfb489f4a014aca\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cetre inscreve servidores municipais para cursos de capacita\u00e7\u00e3o em Jo\u00e3o Pessoa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#website\",\"url\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/\",\"name\":\"Encontra Jo\u00e3o Pessoa\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade Jo\u00e3o Pessoa e regi\u00e3o.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#\/schema\/person\/dcf4dbc803217a030dfb489f4a014aca\",\"name\":\"Encontra Jo\u00e3o Pessoa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"caption\":\"Encontra Jo\u00e3o Pessoa\"},\"url\":\"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/author\/ejoaopessoa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cetre inscreve servidores municipais para cursos de capacita\u00e7\u00e3o em Jo\u00e3o Pessoa - Encontra Jo\u00e3o Pessoa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/","og_locale":"pt_BR","og_type":"article","og_title":"Cetre inscreve servidores municipais para cursos de capacita\u00e7\u00e3o em Jo\u00e3o Pessoa - Encontra Jo\u00e3o Pessoa","og_description":"A Prefeitura Municipal de Jo\u00e3o Pessoa (PMJP), atrav\u00e9s da Secretaria de Administra\u00e7\u00e3o, est\u00e1 oferecendo cursos na cidade de Jo\u00e3o Pessoa de capacita\u00e7\u00e3o para servidores no Centro de Treinamento Miguel Arrais (Cetre), localizado \u00e0 Avenida Piau\u00ed, no Bairro dos Estados. As inscri\u00e7\u00f5es para os cursos dos meses de mar\u00e7o a abril est\u00e3o abertas e ser\u00e3o efetuadas at\u00e9 o preenchimento das vagas. Segundo a diretora de Recursos Humanos da Sead, L\u00edlian Coelho, ser\u00e3o formadas 77 turmas no total, divididas entre os cursos de Inform\u00e1tica, Forma\u00e7\u00e3o e Gest\u00e3o P\u00fablica. \u201cPara os cursos que estamos oferecendo inicialmente, as aulas acontecer\u00e3o nos tr\u00eas turnos, no","og_url":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/","og_site_name":"Encontra Jo\u00e3o Pessoa","article_published_time":"2013-03-13T03:01:06+00:00","author":"Encontra Jo\u00e3o Pessoa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Jo\u00e3o Pessoa","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/","url":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/","name":"Cetre inscreve servidores municipais para cursos de capacita\u00e7\u00e3o em Jo\u00e3o Pessoa - Encontra Jo\u00e3o Pessoa","isPartOf":{"@id":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#website"},"datePublished":"2013-03-13T03:01:06+00:00","author":{"@id":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#\/schema\/person\/dcf4dbc803217a030dfb489f4a014aca"},"breadcrumb":{"@id":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/cetre-inscreve-servidores-municipais-para-cursos-de-capacitacao-em-joao-pessoa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Cetre inscreve servidores municipais para cursos de capacita\u00e7\u00e3o em Jo\u00e3o Pessoa"}]},{"@type":"WebSite","@id":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#website","url":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/","name":"Encontra Jo\u00e3o Pessoa","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade Jo\u00e3o Pessoa e regi\u00e3o.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#\/schema\/person\/dcf4dbc803217a030dfb489f4a014aca","name":"Encontra Jo\u00e3o Pessoa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","caption":"Encontra Jo\u00e3o Pessoa"},"url":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/author\/ejoaopessoa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/wp-json\/wp\/v2\/posts\/185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=185"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/wp-json\/wp\/v2\/posts\/185\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrajoaopessoa.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}